{"id":27006,"date":"2022-10-23T17:05:03","date_gmt":"2022-10-23T17:05:03","guid":{"rendered":"https:\/\/fast-gas.com\/power-up-your-drinks-with-cream-chargers\/"},"modified":"2024-05-05T05:20:54","modified_gmt":"2024-05-05T05:20:54","slug":"alimentez-vos-boissons-avec-des-chargeurs-de-creme","status":"publish","type":"post","link":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/","title":{"rendered":"Alimentez Vos Boissons Avec Des Chargeurs De Cr\u00e8me\u00a0"},"content":{"rendered":"<p>Si vous pensiez que le travail des siphons \u00e0 cr\u00e8me se terminait par de la cr\u00e8me fouett\u00e9e, vous avez tort. Les siphons \u00e0 cr\u00e8me et les <strong>chargeurs de cr\u00e8me<\/strong> sont bien plus utiles que vous ne l&#8217;imaginez. Ces deux-l\u00e0 peuvent \u00eatre la bonne combinaison pour votre prochaine grande f\u00eate.<\/p>\n<p><strong>Ce petit guide vous apprendra ce que sont les infusions rapides et comment en tirer le meilleur parti gr\u00e2ce aux chargeurs de cr\u00e8me.<\/strong><\/p>\n<p style=\"text-align: center;\"><a class=\"button button--primary hero__button\" href=\"https:\/\/fast-gas.com\/fr\/distributeur\/\">Devenez Distributeur<\/a><\/p>\n<h2>Infusions Rapides Avec Des Chargeurs De Cr\u00e8me<\/h2>\n<p>\u00c0 mesure que <strong><a href=\"https:\/\/exotic-whip.com\/fr\/blog-fr\/soyez-a-jour-avec-loxyde-nitreux-et-la-gastronomie-moleculaire\/\">la cuisine moderne<\/a><\/strong> progresse, ce n&#8217;est pas un secret que d&#8217;autres domaines li\u00e9s \u00e0 la restauration pr\u00e9sentent \u00e9galement des innovations significatives.<\/p>\n<p>Une technique classique qui prenait beaucoup de temps \u00e9tait l&#8217;infusion. Quelque chose d&#8217;aussi simple que de placer des herbes, de l&#8217;ail ou des piments dans de l&#8217;alcool ou de l&#8217;huile pour obtenir pleinement une saveur ou une vari\u00e9t\u00e9 sp\u00e9cifique.<\/p>\n<p>Gr\u00e2ce aux chargeurs de cr\u00e8me, les infusions peuvent aujourd&#8217;hui \u00eatre pr\u00eates en quelques minutes au lieu de plusieurs mois, du moins celles de haute qualit\u00e9.\u00a0On les appelle des infusions rapides.<\/p>\n<p>Les infusions rapides sont utilis\u00e9es dans les bars \u00e0 cocktails et les restaurants pour des infusions rapides d&#8217;ar\u00f4mes afin de cr\u00e9er la boisson parfaite, des ar\u00f4mes alimentaires, des sauces, des <strong><a href=\"https:\/\/exotic-whip.com\/fr\/blog-fr\/comment-faire-des-mousses-sucrees-avec-un-siphon-a-creme\/\">mousses<\/a><\/strong> et des mousses.<\/p>\n<h2>Siphons \u00e0 Cr\u00e8me Pour Cr\u00e9er Rapidement Des Infusions De Cocktails Alcoolis\u00e9s<\/h2>\n<p>Parmi les chefs et les barmen, le succ\u00e8s des infusions rapides est indubitable. Non seulement cette technique est plus simple et peu co\u00fbteuse, mais elle est \u00e9galement rapide. Il suffit d&#8217;un <strong><a href=\"https:\/\/fast-gas.com\/fr\/comment-fonctionnent-les-siphons-a-chantilly\/\">distributeur de cr\u00e8me fouett\u00e9e<\/a><\/strong> et d&#8217;un chargeur de cr\u00e8me, par exemple, pour cr\u00e9er un cocktail \u00e0 base d&#8217;alcool.<\/p>\n<p><strong>Mais quel r\u00f4le jouent le siphon \u00e0 cr\u00e8me et le protoxyde d&#8217;azote (N2O) dans ce processus ?\u00a0<\/strong><\/p>\n<p>L&#8217;utilisation d&#8217;un siphon \u00e0 cr\u00e8me vous permet de capturer les compos\u00e9s bruts frais des ingr\u00e9dients solides que vous souhaitez infuser dans l&#8217;huile ou l&#8217;alcool sans avoir besoin de chaleur.<\/p>\n<p>Le N2O, quant \u00e0 lui, est la raison pour laquelle l&#8217;infusion rapide fonctionne. La pression du N2O dilate les parois cellulaires du liquide dans le siphon et permet au liquide de s&#8217;\u00e9couler facilement.<\/p>\n<p>Plus le liquide peut passer \u00e0 travers les ingr\u00e9dients solides, plus vous obtiendrez de saveur.<\/p>\n<p><strong>Vous avez besoin d&#8217;inspiration pour cr\u00e9er votre prochain cocktail \u00e0 base d&#8217;alcool ?<\/strong>\u00a0<strong><a href=\"https:\/\/exotic-whip.com\/fr\/blog-fr\/soyez-a-jour-avec-loxyde-nitreux-et-la-gastronomie-moleculaire\/\"> Consultez la recette de ce guide<\/a><\/strong>.<\/p>\n<h2>Fastgas &#8211; Bouteilles de N2O Vente En Gros<\/h2>\n<p>Les chargeurs de cr\u00e8me sont sans aucun doute un excellent moyen de dynamiser vos boissons, et vous en \u00eates maintenant s\u00fbr.<\/p>\n<p>Si vous aimez acheter des chargeurs de cr\u00e8me prochainement pour essayer certaines recettes trouv\u00e9es en ligne, vous devriez opter pour la meilleure marque du march\u00e9 : FastGas.<\/p>\n<p><strong><a href=\"https:\/\/fast-gas.com\/fr\/\">FastGas<\/a><\/strong> est une bonbonne jetable de 640gr, id\u00e9ale pour un remplissage plus rapide. Elle \u00e9quivaut \u00e0 environ 85+ bidons de cr\u00e8me traditionnels.<\/p>\n<p><strong><a href=\"https:\/\/fast-gas.com\/fr\/product-category\/tous\/\">D\u00e9couvrez tous nos produits ici.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vous pensiez que le travail des siphons \u00e0 cr\u00e8me se terminait par de la cr\u00e8me fouett\u00e9e, vous avez tort. Les siphons \u00e0 cr\u00e8me et les chargeurs de cr\u00e8me sont bien plus utiles que vous ne l&#8217;imaginez. Ces deux-l\u00e0 peuvent \u00eatre la bonne combinaison pour votre prochaine grande f\u00eate. Ce petit guide vous apprendra ce [&hellip;]<\/p>\n","protected":false},"author":5216,"featured_media":25495,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-27006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alimentez Vos Boissons Avec Des Chargeurs De Cr\u00e8me\u00a0 | FastGas<\/title>\n<meta name=\"description\" content=\"Ce petit guide vous apprendra ce que sont les infusions rapides et comment en tirer le meilleur parti en utilisant des chargeurs de cr\u00e8me. Regardez-le !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alimentez Vos Boissons Avec Des Chargeurs De Cr\u00e8me\u00a0 | FastGas\" \/>\n<meta property=\"og:description\" content=\"Ce petit guide vous apprendra ce que sont les infusions rapides et comment en tirer le meilleur parti en utilisant des chargeurs de cr\u00e8me. Regardez-le !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/\" \/>\n<meta property=\"og:site_name\" content=\"FastGas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/wearefastgas\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-23T17:05:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-05T05:20:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fast-gas.com\/wp-content\/uploads\/2022\/10\/alcohol-gff4771533_1920.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1282\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bro FastGas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bro FastGas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/\"},\"author\":{\"name\":\"Bro FastGas\",\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/#\\\/schema\\\/person\\\/4b3a9beffb469faf985fef2c2b684689\"},\"headline\":\"Alimentez Vos Boissons Avec Des Chargeurs De Cr\u00e8me\u00a0\",\"datePublished\":\"2022-10-23T17:05:03+00:00\",\"dateModified\":\"2024-05-05T05:20:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/\"},\"wordCount\":526,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fast-gas.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/alcohol-gff4771533_1920.jpeg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/\",\"url\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/\",\"name\":\"Alimentez Vos Boissons Avec Des Chargeurs De Cr\u00e8me\u00a0 | FastGas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fast-gas.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/alcohol-gff4771533_1920.jpeg\",\"datePublished\":\"2022-10-23T17:05:03+00:00\",\"dateModified\":\"2024-05-05T05:20:54+00:00\",\"description\":\"Ce petit guide vous apprendra ce que sont les infusions rapides et comment en tirer le meilleur parti en utilisant des chargeurs de cr\u00e8me. Regardez-le !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fast-gas.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/alcohol-gff4771533_1920.jpeg\",\"contentUrl\":\"https:\\\/\\\/fast-gas.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/alcohol-gff4771533_1920.jpeg\",\"width\":1920,\"height\":1282,\"caption\":\"cream chargers - infused cocktail\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alimentez Vos Boissons Avec Des Chargeurs De Cr\u00e8me\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/\",\"name\":\"FastGas\",\"description\":\"N2O Cream Chargers\",\"publisher\":{\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/#organization\",\"name\":\"FastGas - Helium, CO2 & N2O Wholesale\",\"alternateName\":\"Fast Gas\",\"url\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fast-gas.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-Fastgas-Favicon.png\",\"contentUrl\":\"https:\\\/\\\/fast-gas.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-Fastgas-Favicon.png\",\"width\":512,\"height\":512,\"caption\":\"FastGas - Helium, CO2 & N2O Wholesale\"},\"image\":{\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/wearefastgas\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCV5w9vrihWFu0yM7SZzQfVQ\\\/videos\",\"https:\\\/\\\/instagram.com\\\/fastgas.official\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/#\\\/schema\\\/person\\\/4b3a9beffb469faf985fef2c2b684689\",\"name\":\"Bro FastGas\",\"description\":\"Meet our Culinary Gas &amp; Tech Editor: pioneering N2O, CO2, and cream charger innovations with recipes, reviews, and cutting-edge insights.\",\"url\":\"https:\\\/\\\/fast-gas.com\\\/fr\\\/author\\\/iryna\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alimentez Vos Boissons Avec Des Chargeurs De Cr\u00e8me\u00a0 | FastGas","description":"Ce petit guide vous apprendra ce que sont les infusions rapides et comment en tirer le meilleur parti en utilisant des chargeurs de cr\u00e8me. Regardez-le !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/","og_locale":"fr_FR","og_type":"article","og_title":"Alimentez Vos Boissons Avec Des Chargeurs De Cr\u00e8me\u00a0 | FastGas","og_description":"Ce petit guide vous apprendra ce que sont les infusions rapides et comment en tirer le meilleur parti en utilisant des chargeurs de cr\u00e8me. Regardez-le !","og_url":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/","og_site_name":"FastGas","article_publisher":"https:\/\/facebook.com\/wearefastgas","article_published_time":"2022-10-23T17:05:03+00:00","article_modified_time":"2024-05-05T05:20:54+00:00","og_image":[{"width":1920,"height":1282,"url":"https:\/\/fast-gas.com\/wp-content\/uploads\/2022\/10\/alcohol-gff4771533_1920.jpeg","type":"image\/jpeg"}],"author":"Bro FastGas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bro FastGas","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/#article","isPartOf":{"@id":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/"},"author":{"name":"Bro FastGas","@id":"https:\/\/fast-gas.com\/fr\/#\/schema\/person\/4b3a9beffb469faf985fef2c2b684689"},"headline":"Alimentez Vos Boissons Avec Des Chargeurs De Cr\u00e8me\u00a0","datePublished":"2022-10-23T17:05:03+00:00","dateModified":"2024-05-05T05:20:54+00:00","mainEntityOfPage":{"@id":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/"},"wordCount":526,"commentCount":0,"publisher":{"@id":"https:\/\/fast-gas.com\/fr\/#organization"},"image":{"@id":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/#primaryimage"},"thumbnailUrl":"https:\/\/fast-gas.com\/wp-content\/uploads\/2022\/10\/alcohol-gff4771533_1920.jpeg","articleSection":["Blog"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/","url":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/","name":"Alimentez Vos Boissons Avec Des Chargeurs De Cr\u00e8me\u00a0 | FastGas","isPartOf":{"@id":"https:\/\/fast-gas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/#primaryimage"},"image":{"@id":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/#primaryimage"},"thumbnailUrl":"https:\/\/fast-gas.com\/wp-content\/uploads\/2022\/10\/alcohol-gff4771533_1920.jpeg","datePublished":"2022-10-23T17:05:03+00:00","dateModified":"2024-05-05T05:20:54+00:00","description":"Ce petit guide vous apprendra ce que sont les infusions rapides et comment en tirer le meilleur parti en utilisant des chargeurs de cr\u00e8me. Regardez-le !","breadcrumb":{"@id":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/#primaryimage","url":"https:\/\/fast-gas.com\/wp-content\/uploads\/2022\/10\/alcohol-gff4771533_1920.jpeg","contentUrl":"https:\/\/fast-gas.com\/wp-content\/uploads\/2022\/10\/alcohol-gff4771533_1920.jpeg","width":1920,"height":1282,"caption":"cream chargers - infused cocktail"},{"@type":"BreadcrumbList","@id":"https:\/\/fast-gas.com\/fr\/alimentez-vos-boissons-avec-des-chargeurs-de-creme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fast-gas.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Alimentez Vos Boissons Avec Des Chargeurs De Cr\u00e8me\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/fast-gas.com\/fr\/#website","url":"https:\/\/fast-gas.com\/fr\/","name":"FastGas","description":"N2O Cream Chargers","publisher":{"@id":"https:\/\/fast-gas.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fast-gas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fast-gas.com\/fr\/#organization","name":"FastGas - Helium, CO2 & N2O Wholesale","alternateName":"Fast Gas","url":"https:\/\/fast-gas.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fast-gas.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fast-gas.com\/wp-content\/uploads\/2025\/03\/cropped-Fastgas-Favicon.png","contentUrl":"https:\/\/fast-gas.com\/wp-content\/uploads\/2025\/03\/cropped-Fastgas-Favicon.png","width":512,"height":512,"caption":"FastGas - Helium, CO2 & N2O Wholesale"},"image":{"@id":"https:\/\/fast-gas.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/wearefastgas","https:\/\/www.youtube.com\/channel\/UCV5w9vrihWFu0yM7SZzQfVQ\/videos","https:\/\/instagram.com\/fastgas.official"]},{"@type":"Person","@id":"https:\/\/fast-gas.com\/fr\/#\/schema\/person\/4b3a9beffb469faf985fef2c2b684689","name":"Bro FastGas","description":"Meet our Culinary Gas &amp; Tech Editor: pioneering N2O, CO2, and cream charger innovations with recipes, reviews, and cutting-edge insights.","url":"https:\/\/fast-gas.com\/fr\/author\/iryna\/"}]}},"_links":{"self":[{"href":"https:\/\/fast-gas.com\/fr\/wp-json\/wp\/v2\/posts\/27006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fast-gas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fast-gas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fast-gas.com\/fr\/wp-json\/wp\/v2\/users\/5216"}],"replies":[{"embeddable":true,"href":"https:\/\/fast-gas.com\/fr\/wp-json\/wp\/v2\/comments?post=27006"}],"version-history":[{"count":4,"href":"https:\/\/fast-gas.com\/fr\/wp-json\/wp\/v2\/posts\/27006\/revisions"}],"predecessor-version":[{"id":35443,"href":"https:\/\/fast-gas.com\/fr\/wp-json\/wp\/v2\/posts\/27006\/revisions\/35443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fast-gas.com\/fr\/wp-json\/wp\/v2\/media\/25495"}],"wp:attachment":[{"href":"https:\/\/fast-gas.com\/fr\/wp-json\/wp\/v2\/media?parent=27006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fast-gas.com\/fr\/wp-json\/wp\/v2\/categories?post=27006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fast-gas.com\/fr\/wp-json\/wp\/v2\/tags?post=27006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}